{"id":17013,"count":1,"description":"","link":"https:\/\/1eyesex.com\/videos\/actor\/natasha-polynesia\/","name":"Natasha Polynesia","slug":"natasha-polynesia","taxonomy":"actors","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Natasha Polynesia Archives - 1 Eye Sex<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/1eyesex.com\/videos\/actor\/natasha-polynesia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Natasha Polynesia Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/1eyesex.com\/videos\/actor\/natasha-polynesia\/\" \/>\n<meta property=\"og:site_name\" content=\"1 Eye Sex\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/1eyesex.com\\\/videos\\\/actor\\\/natasha-polynesia\\\/\",\"url\":\"https:\\\/\\\/1eyesex.com\\\/videos\\\/actor\\\/natasha-polynesia\\\/\",\"name\":\"Natasha Polynesia Archives - 1 Eye Sex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/1eyesex.com\\\/videos\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/1eyesex.com\\\/videos\\\/actor\\\/natasha-polynesia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/1eyesex.com\\\/videos\\\/actor\\\/natasha-polynesia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/1eyesex.com\\\/videos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Natasha Polynesia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/1eyesex.com\\\/videos\\\/#website\",\"url\":\"https:\\\/\\\/1eyesex.com\\\/videos\\\/\",\"name\":\"1 Eye Sex\",\"description\":\"Free High Quality XXX Porn\",\"publisher\":{\"@id\":\"https:\\\/\\\/1eyesex.com\\\/videos\\\/#\\\/schema\\\/person\\\/56cb6f3467d8249d0229f3616d6decbb\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/1eyesex.com\\\/videos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/1eyesex.com\\\/videos\\\/#\\\/schema\\\/person\\\/56cb6f3467d8249d0229f3616d6decbb\",\"name\":\"1 Eye Sex\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb3e0c380aaa5883ff2be6d8a4a83f11a99d8104127fd9e2166a96c1a38a1eee?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb3e0c380aaa5883ff2be6d8a4a83f11a99d8104127fd9e2166a96c1a38a1eee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb3e0c380aaa5883ff2be6d8a4a83f11a99d8104127fd9e2166a96c1a38a1eee?s=96&d=mm&r=g\",\"caption\":\"1 Eye Sex\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb3e0c380aaa5883ff2be6d8a4a83f11a99d8104127fd9e2166a96c1a38a1eee?s=96&d=mm&r=g\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Natasha Polynesia Archives - 1 Eye Sex","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/1eyesex.com\/videos\/actor\/natasha-polynesia\/","og_locale":"en_US","og_type":"article","og_title":"Natasha Polynesia Archives","og_url":"https:\/\/1eyesex.com\/videos\/actor\/natasha-polynesia\/","og_site_name":"1 Eye Sex","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/1eyesex.com\/videos\/actor\/natasha-polynesia\/","url":"https:\/\/1eyesex.com\/videos\/actor\/natasha-polynesia\/","name":"Natasha Polynesia Archives - 1 Eye Sex","isPartOf":{"@id":"https:\/\/1eyesex.com\/videos\/#website"},"breadcrumb":{"@id":"https:\/\/1eyesex.com\/videos\/actor\/natasha-polynesia\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/1eyesex.com\/videos\/actor\/natasha-polynesia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/1eyesex.com\/videos\/"},{"@type":"ListItem","position":2,"name":"Natasha Polynesia"}]},{"@type":"WebSite","@id":"https:\/\/1eyesex.com\/videos\/#website","url":"https:\/\/1eyesex.com\/videos\/","name":"1 Eye Sex","description":"Free High Quality XXX Porn","publisher":{"@id":"https:\/\/1eyesex.com\/videos\/#\/schema\/person\/56cb6f3467d8249d0229f3616d6decbb"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/1eyesex.com\/videos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/1eyesex.com\/videos\/#\/schema\/person\/56cb6f3467d8249d0229f3616d6decbb","name":"1 Eye Sex","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/fb3e0c380aaa5883ff2be6d8a4a83f11a99d8104127fd9e2166a96c1a38a1eee?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fb3e0c380aaa5883ff2be6d8a4a83f11a99d8104127fd9e2166a96c1a38a1eee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fb3e0c380aaa5883ff2be6d8a4a83f11a99d8104127fd9e2166a96c1a38a1eee?s=96&d=mm&r=g","caption":"1 Eye Sex"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/fb3e0c380aaa5883ff2be6d8a4a83f11a99d8104127fd9e2166a96c1a38a1eee?s=96&d=mm&r=g"}}]}},"_links":{"self":[{"href":"https:\/\/1eyesex.com\/videos\/wp-json\/wp\/v2\/actors\/17013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/1eyesex.com\/videos\/wp-json\/wp\/v2\/actors"}],"about":[{"href":"https:\/\/1eyesex.com\/videos\/wp-json\/wp\/v2\/taxonomies\/actors"}],"wp:post_type":[{"href":"https:\/\/1eyesex.com\/videos\/wp-json\/wp\/v2\/posts?actors=17013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}